{"id":5084,"date":"2023-06-01T15:50:25","date_gmt":"2023-06-01T13:50:25","guid":{"rendered":"https:\/\/www.cimsystem.com\/industrial\/?post_type=news&#038;p=5084"},"modified":"2024-01-11T15:18:16","modified_gmt":"2024-01-11T14:18:16","slug":"cimsystem-timbrificio-rossi-made-in-italy","status":"publish","type":"news","link":"https:\/\/www.cimsystem.com\/industrial\/it\/news\/cimsystem-timbrificio-rossi-made-in-italy\/","title":{"rendered":"MANIFATTURA E MADE IN ITALY:\u00a0 un binomio senza tempo con CIMsystem &#038; Timbrificio Rossi"},"content":{"rendered":"<section class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text]<strong>L&#8217;esigenza di snellire i flussi di lavoro ha portato Timbrificio Rossi a rivedere alcuni asset presenti in azienda, dando maggior spazio e rilevanza all&#8217;integrazione dei sistemi. Come \u00e8 noto, avere sistemi integrati che semplifichino l&#8217;esperienza d&#8217;uso dell&#8217;utente \u00e8 fondamentale per ottimizzare le tempistiche di apprendimento ed utilizzo delle apparecchiature.\u00a0 Timbrificio Rossi &amp; CIMsystem creano un binomio che fonda le proprie radici nell&#8217;esperienza pluriennale ma guarda al futuro.\u00a0<\/strong>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space height=&#8221;16px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]Siamo nel 1982 quando la famiglia Rossi fonda, nel maceratese, il proprio timbrificio, con lo scopo di fornire alle numerose aziende calzaturiere e della pelletteria del territorio, un prodotto di qualit\u00e0 per lo stampaggio di pellami e suole.\r\n\r\nIl timbrificio <a href=\"http:\/\/www.timbrificio.net\"><strong>Timbrificio Rossi snc<\/strong><\/a> ha una storia fatta di qualit\u00e0 ed efficienza, propria del Made in Italy. Negli anni le tipologie di prodotti forniti sono aumentate e l\u2019innovazione tecnologica \u00e8 stata la chiave per poter soddisfare le esigenze di un mercato sempre pi\u00f9 dinamico.\r\n\r\nOggi l\u2019azienda riesce a fornire un ampio assortimento di prodotti quali: timbri in ottone per pelle, timbri in ottone per cuoio, piastre per marcatura pelle, stampi in generale; produce timbri in gomma per ufficio e targhe, timbri in metallo, piastre per placcatrici e fustelle ricavate, oltre a prototipi per la fusione in zama. Negli ultimi 10 anni poi, l\u2019azienda \u00e8 entrata nel mondo della produzione in serie di particolari in ottone e alluminio per settore moda e meccanica.\r\n\r\nA sostegno di una ricerca continua nell\u2019ambito delle ultime innovazioni del settore manifatturiero, il Timbrificio ha selezionato CIMsystem come partner tecnologico. Abbiamo intervistato <strong>Anthony Rossi che ci spiega perch\u00e9 la scelta si \u00e8 orientata verso la soluzione <a href=\"https:\/\/www.cimsystem.com\/industrial\/it\/products\/rhinonc\/\">RhinoNC di CIMsystem<\/a><\/strong>.\r\n\r\n\u201cAbbiamo scelto il CAM 3D RhinoNC perch\u00e9 \u00e8 perfettamente integrato nel <a href=\"https:\/\/www.cimsystem.com\/industrial\/it\/products\/rhinoceros\/\"><strong>CAD Rhinoceros<\/strong>.<\/a> Il nostro team tecnico era gi\u00e0 in possesso di un know-how del software CAD Rhino e necessitavamo di utilizzare un CAM che fosse completamente integrato con l\u2019interfaccia gi\u00e0 di nostro utilizzo.\u201d\r\n\r\nInfatti, l\u2019interfaccia del CAM \u00e8 estremamente semplificata, sia per un principiante sia per un utente esperto. L\u2019estrema semplicit\u00e0 dell\u2019interfaccia permette a qualsiasi operatore di cercare le icone principali ma anche di individuare funzionalit\u00e0 pi\u00f9 specifiche.\r\n\r\n<strong>Come afferma il Sig. Rossi<\/strong>, \u201cil software si \u00e8 inserito molto facilmente all\u2019interno della quotidianit\u00e0 lavorativa, soprattutto per quanto riguarda l\u2019operativit\u00e0 dei flussi di produzione, questo grazie anche alla conoscenza del CAD Rhino da parte del nostro reparto tecnico\u201d.\r\n\r\nL\u2019adozione di una soluzione completa come il CAM di CIMsystem ha rivoluzionato i flussi di lavoro all\u2019interno della realt\u00e0 maceratese. Nello specifico si \u00e8 ottenuta una migliore gestione degli input e degli output degli utensili, delle frese e quindi di tutte le varie opzioni che si possono utilizzare per l\u2019approccio in fresatura. Inoltre, grazie alla funzione di simulazione della lavorazione in corso, mostrando l\u2019asportazione che crea l\u2019utensile per ogni passata, \u00e8 migliorata la ricerca e la segnalazione di eventuali errori durante le fasi di calcolo.\r\n\r\nA tal riguardo Anthony Rossi si \u00e8 dimostrato entusiasta della scelta di RhinoNC per stampi di pellami e suole, lodandone la sua facilit\u00e0 di utilizzo e la sua competitivit\u00e0<strong>. <\/strong>\u201cLa peculiarit\u00e0 del software \u00e8 proprio la sua interscambiabilit\u00e0 con altri sistemi e la sua versatilit\u00e0; questo rende il CAM una garanzia a lungo termine per un programma in continuo sviluppo\u201d.\r\n\r\nLa versatilit\u00e0 multi-tasking del programma \u00e8 in grado di assicurare anche una gestione simultanea di pi\u00f9 progetti e lavorazioni, restituendo al cliente una consegna pronta e precisa, con tempi di lavoro ridotti e la possibilit\u00e0 di errori manuali minimizzata.\r\n\r\nSapersi rinnovare e innovare sono caratteristiche che hanno fatto del Made in Italy un concetto intramontabile, che permette ad aziende come Timbrificio Rossi e <a href=\"http:\/\/www.cimsystem.com\"><strong>CIMsystem<\/strong><\/a> di porsi in maniera competitiva ma efficace sul mercato fornendo prodotti finiti di qualit\u00e0 al passo coi tempi e con le risorse.[\/vc_column_text][\/vc_column][\/vc_row]<\/section>","protected":false},"excerpt":{"rendered":"Leader nello sviluppo e nella commercializzazione di software CAD\/CAM per la manifattura industriale e il settore odontoiatrico, CIMsystem ha affiancato Timbrificio Rossi fornendo a questa realt\u00e0 maceratese soluzioni innovative.\r\n\r\n<a href=\"https:\/\/www.cimsystem.com\/industrial\/it\/news\/cimsystem-timbrificio-rossi-made-in-italy\/\" target=\"_blank\" rel=\"noopener\"><strong>Leggi di pi\u00f9<\/strong><\/a>","protected":false},"featured_media":5138,"template":"","news-categories":[32],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.cimsystem.com\/industrial\/it\/wp-json\/wp\/v2\/news\/5084"}],"collection":[{"href":"https:\/\/www.cimsystem.com\/industrial\/it\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/www.cimsystem.com\/industrial\/it\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cimsystem.com\/industrial\/it\/wp-json\/wp\/v2\/media\/5138"}],"wp:attachment":[{"href":"https:\/\/www.cimsystem.com\/industrial\/it\/wp-json\/wp\/v2\/media?parent=5084"}],"wp:term":[{"taxonomy":"news-categories","embeddable":true,"href":"https:\/\/www.cimsystem.com\/industrial\/it\/wp-json\/wp\/v2\/news-categories?post=5084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}